{"id":53,"date":"2021-03-04T17:48:25","date_gmt":"2021-03-04T17:48:25","guid":{"rendered":"https:\/\/aziendapluriserviziportorecanati.it\/?page_id=53"},"modified":"2021-04-13T14:38:52","modified_gmt":"2021-04-13T14:38:52","slug":"amministrazione-trasparente","status":"publish","type":"page","link":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/","title":{"rendered":"Societ\u00e0 Trasparente"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"53\" class=\"elementor elementor-53\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6305e797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6305e797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e9e90cf\" data-id=\"1e9e90cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25e8c79b elementor-widget elementor-widget-text-editor\" data-id=\"25e8c79b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<h2 class=\"wp-block-heading\">Societ\u00e0 trasparente<\/h2>\n<p><\/p>\n<div class=\"x_wpb_text_column x_wpb_content_element\">\n<div class=\"x_wpb_wrapper\">\n<p class=\"wp-block-paragraph\"><em>La presente sezione, \u201cSociet\u00e0 Trasparente\u201d, \u00e8 attualmente in fase di aggiornamento come da disposizioni del decreto legislativo n\u00b0 33\/2013 e provvedimento n\u00b0 243 del 15 maggio 2014 del Garante per la protezione dei dati personali.<\/em><\/p>\n<\/div>\n<\/div>\n<div class=\"x_separator x_transparent\">\u00a0<\/div>\n<div class=\"x_wpb_text_column x_wpb_content_element\">\n<div class=\"x_wpb_wrapper\">\n<p><strong>NOTE PER LA CONSULTAZIONE E L`UTILIZZO DEI DATI<\/strong><\/p>\n<p>I dati personali pubblicati sono \u201criutilizzabili solo alle condizioni previste dalla normativa vigente sul riuso dei dati pubblici (direttiva comunitaria 2003\/98\/CE e d. lgs. 36\/2006 di recepimento della stessa), in termini compatibili con gli scopi per i quali sono stati raccolti e registrati, e nel rispetto della normativa in materia di protezione dei dati personali<\/p>\n<\/div>\n<\/div>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Societ\u00e0 trasparente La presente sezione, \u201cSociet\u00e0 Trasparente\u201d, \u00e8 attualmente in fase di aggiornamento come da disposizioni del decreto legislativo n\u00b0 33\/2013 e provvedimento n\u00b0 243 del 15 maggio 2014 del Garante per la protezione dei dati personali. \u00a0 NOTE PER LA CONSULTAZIONE E L`UTILIZZO DEI DATI I dati personali pubblicati sono \u201criutilizzabili solo alle condizioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"zakra_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"class_list":["post-53","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche\" \/>\n<meta property=\"og:description\" content=\"Societ\u00e0 trasparente La presente sezione, \u201cSociet\u00e0 Trasparente\u201d, \u00e8 attualmente in fase di aggiornamento come da disposizioni del decreto legislativo n\u00b0 33\/2013 e provvedimento n\u00b0 243 del 15 maggio 2014 del Garante per la protezione dei dati personali. \u00a0 NOTE PER LA CONSULTAZIONE E L`UTILIZZO DEI DATI I dati personali pubblicati sono \u201criutilizzabili solo alle condizioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/\" \/>\n<meta property=\"og:site_name\" content=\"Farmacia Comunale di Montalto delle Marche\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T14:38:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/index.php\\\/amministrazione-trasparente\\\/\",\"url\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/index.php\\\/amministrazione-trasparente\\\/\",\"name\":\"Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#website\"},\"datePublished\":\"2021-03-04T17:48:25+00:00\",\"dateModified\":\"2021-04-13T14:38:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/index.php\\\/amministrazione-trasparente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/farmaciamontaltomarche.it\\\/index.php\\\/amministrazione-trasparente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/index.php\\\/amministrazione-trasparente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Societ\u00e0 Trasparente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#website\",\"url\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/\",\"name\":\"Farmacia Comunale di Montalto delle Marche\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#organization\",\"name\":\"Farmacia Comunale di Montalto delle Marche\",\"url\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Montalto_stemma.png\",\"contentUrl\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Montalto_stemma.png\",\"width\":75,\"height\":75,\"caption\":\"Farmacia Comunale di Montalto delle Marche\"},\"image\":{\"@id\":\"https:\\\/\\\/farmaciamontaltomarche.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/","og_locale":"it_IT","og_type":"article","og_title":"Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche","og_description":"Societ\u00e0 trasparente La presente sezione, \u201cSociet\u00e0 Trasparente\u201d, \u00e8 attualmente in fase di aggiornamento come da disposizioni del decreto legislativo n\u00b0 33\/2013 e provvedimento n\u00b0 243 del 15 maggio 2014 del Garante per la protezione dei dati personali. \u00a0 NOTE PER LA CONSULTAZIONE E L`UTILIZZO DEI DATI I dati personali pubblicati sono \u201criutilizzabili solo alle condizioni [&hellip;]","og_url":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/","og_site_name":"Farmacia Comunale di Montalto delle Marche","article_modified_time":"2021-04-13T14:38:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/","url":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/","name":"Societ\u00e0 Trasparente - Farmacia Comunale di Montalto delle Marche","isPartOf":{"@id":"https:\/\/farmaciamontaltomarche.it\/#website"},"datePublished":"2021-03-04T17:48:25+00:00","dateModified":"2021-04-13T14:38:52+00:00","breadcrumb":{"@id":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/farmaciamontaltomarche.it\/index.php\/amministrazione-trasparente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/farmaciamontaltomarche.it\/"},{"@type":"ListItem","position":2,"name":"Societ\u00e0 Trasparente"}]},{"@type":"WebSite","@id":"https:\/\/farmaciamontaltomarche.it\/#website","url":"https:\/\/farmaciamontaltomarche.it\/","name":"Farmacia Comunale di Montalto delle Marche","description":"","publisher":{"@id":"https:\/\/farmaciamontaltomarche.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/farmaciamontaltomarche.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/farmaciamontaltomarche.it\/#organization","name":"Farmacia Comunale di Montalto delle Marche","url":"https:\/\/farmaciamontaltomarche.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/farmaciamontaltomarche.it\/#\/schema\/logo\/image\/","url":"https:\/\/farmaciamontaltomarche.it\/wp-content\/uploads\/2022\/05\/Montalto_stemma.png","contentUrl":"https:\/\/farmaciamontaltomarche.it\/wp-content\/uploads\/2022\/05\/Montalto_stemma.png","width":75,"height":75,"caption":"Farmacia Comunale di Montalto delle Marche"},"image":{"@id":"https:\/\/farmaciamontaltomarche.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/pages\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":56,"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/pages\/53\/revisions"}],"predecessor-version":[{"id":267,"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/pages\/53\/revisions\/267"}],"wp:attachment":[{"href":"https:\/\/farmaciamontaltomarche.it\/index.php\/wp-json\/wp\/v2\/media?parent=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}